{"id":1062,"date":"2018-09-11T19:48:23","date_gmt":"2018-09-11T10:48:23","guid":{"rendered":"https:\/\/www.aleph-inc.co.jp\/recruit\/?page_id=1062"},"modified":"2020-04-15T14:35:29","modified_gmt":"2020-04-15T05:35:29","slug":"1day_10","status":"publish","type":"page","link":"https:\/\/www.aleph-inc.co.jp\/recruit\/staff\/1day_10\/","title":{"rendered":"\u3073\u3063\u304f\u308a\u30c9\u30f3\u30ad\u30fc\u3000S.Y.\u3055\u3093\u306e1\u65e5 10"},"content":{"rendered":"\t<!--\u30bf\u30a4\u30c8\u30eb \u3053\u3053\u304b\u3089-->\r\n\t\t\t<div class=\"title_area bg staff_1day\">\r\n\t\t\t\t<h2 class=\"t_a_c\">\r\n\t\t\t\t\t<img src=\"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-content\/themes\/aleph-recruit\/img\/staff\/title_staff_02.png\" class=\"pc\" alt=\"\u6d3b\u8e8d\u3059\u308b\u793e\u54e1\u306e\u7d39\u4ecb 1\u65e5\u306e\u6d41\u308c\">\r\n\t\t\t\t\t<img src=\"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-content\/themes\/aleph-recruit\/img\/staff\/title_staff_02_sp.png\" class=\"sp\" alt=\"\u6d3b\u8e8d\u3059\u308b\u793e\u54e1\u306e\u7d39\u4ecb 1\u65e5\u306e\u6d41\u308c\">\r\n\t\t\t\t<\/h2>\r\n\t\t\t<\/div>\r\n\t\t\t<!--\u30bf\u30a4\u30c8\u30eb \u3053\u3053\u307e\u3067-->\r\n\t\t\t<!--\u30b3\u30f3\u30c6\u30f3\u30c4 \u3053\u3053\u304b\u3089-->\r\n\t\t\t<div class=\"inner_middle cf staff_1day\">\r\n\t\t\t\t<!--\u9854\u753b\u50cf \u3053\u3053\u304b\u3089-->\r\n\t\t\t\t<div class=\"face_area\">\r\n\t\t\t\t\t<div class=\"cercle\">\r\n\t\t\t\t\t\t<img src=\"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-content\/themes\/aleph-recruit\/img\/staff\/1day_10_main.jpg\" alt=\"\u95a2\u6771\u5730\u533a S.Y\u3055\u3093\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<h3><span>\u3073\u3063\u304f\u308a\u30c9\u30f3\u30ad\u30fc<\/span>S.Y.<em>\u3055\u3093\u306e1\u65e5<\/em><\/h3>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<!--\u9854\u753b\u50cf \u3053\u3053\u307e\u3067-->\r\n\t\t\t\t<!--\u6642\u7cfb\u5217 \u3053\u3053\u304b\u3089-->\r\n\t\t\t\t<div class=\"timeline\">\r\n\t\t\t\t\t<h4 class=\"wow fadeInLeft\"><span>17:00<\/span>\u51fa\u52e4<\/h4>\r\n\t\t\t\t\t<!--\u753b\u50cf\u53f3 \u3053\u3053\u304b\u3089-->\r\n\t\t\t\t\t<ul class=\"pict_right\">\r\n\t\t\t\t\t\t<li class=\"wow fadeInRight\"><img src=\"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-content\/themes\/aleph-recruit\/img\/staff\/1day_10_01.jpg\" alt=\"\u95a2\u6771\u5730\u533a S.Y\u3055\u3093\"><\/li>\r\n\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t<div>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInLeft\">\u81ea\u52d5\u8eca\u901a\u52e4 \u6c17\u6301\u3061\u3092\u4ed5\u4e8b\u30e2\u30fc\u30c9\u306b<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInLeft\">\u30b9\u30bf\u30c3\u30d5\u306e\u7686\u3055\u3093\u306b\u6328\u62f6\u3057\u306a\u304c\u3089\u52e4\u52d9\u72b6\u6cc1\u306e\u78ba\u8a8d<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInLeft\">\u30b9\u30bf\u30c3\u30d5\u306e\u4f53\u8abf\u30fb\u8eab\u3060\u3057\u306a\u307f\u3092\u78ba\u8a8d<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInLeft\">\u5236\u670d\u306b\u7740\u66ff\u3048\u3001\u624b\u3092\u3088\u304f\u6d17\u3044\u3001\u52e4\u52d9\u306b\u3080\u3051\u3066\u6e96\u5099OK<\/span>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t<!--\u753b\u50cf\u53f3 \u3053\u3053\u307e\u3067-->\r\n\t\t\t\t\t<!--\u753b\u50cf\u5de6 \u3053\u3053\u304b\u3089-->\r\n\t\t\t\t\t<ul class=\"pict_left\">\r\n\t\t\t\t\t\t<li class=\"wow fadeInLeft\"><img src=\"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-content\/themes\/aleph-recruit\/img\/staff\/1day_10_02.jpg\" alt=\"\u95a2\u6771\u5730\u533a S.Y\u3055\u3093\"><\/li>\r\n\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t<div>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInRight\">\u65b0\u4eba\u30b9\u30bf\u30c3\u30d5\u306e\u30c8\u30ec\u30fc\u30cb\u30f3\u30b0\u3092\u3057\u307e\u3059<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInRight\">\u5e97\u5185\u306e\u5ba4\u6e29\u3084\u97f3\u697d\u306e\u5927\u304d\u3055\u306a\u3069\u304a\u5ba2\u69d8\u304c\u5feb\u9069\u306b\u904e\u3054\u3057\u3066\u3044\u308b\u304b\u78ba\u8a8d<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInRight\">\u30ad\u30c3\u30c1\u30f3\u3068\u30db\u30fc\u30eb\u306e\u4f5c\u696d\u5272\u3092\u3057\u307e\u3059<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInRight\">\u4f7f\u7528\u5099\u54c1\u306e\u5728\u5eab\u78ba\u8a8d\u3001\u767a\u6ce8\u3084\u4ed5\u8fbc\u307f\u57fa\u6e96\u3092\u8abf\u6574\u3057\u307e\u3059<\/span>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t<!--\u753b\u50cf\u5de6 \u3053\u3053\u307e\u3067-->\r\n\t\t\t\t\t<h4 class=\"wow fadeInLeft\"><span>21:00<\/span>\u4f11\u61a9<\/h4>\r\n\t\t\t\t\t<!--\u753b\u50cf\u53f3 \u3053\u3053\u304b\u3089-->\r\n\t\t\t\t\t<ul class=\"pict_right lunch\">\r\n\t\t\t\t\t\t<li><!--<img src=\"[template_url]\/img\/staff\/1day_10_02.jpg\" alt=\"\u95a2\u6771\u5730\u533a S.Y\u3055\u3093\">--><\/li>\r\n\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t<div>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInLeft\">\u4f11\u61a9\u5ba4\u3067\u30d1\u30fc\u30c8\u30ca\u30fc\u3055\u3093\u3068\u304a\u3057\u3083\u3079\u308a\u3057\u305f\u308a\u3001\u8efd\u98df\u3092\u98df\u3079\u305f\u308a\u3067\u3059<\/span>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t<!--\u753b\u50cf\u53f3 \u3053\u3053\u307e\u3067-->\r\n\t\t\t\t\t<h4 class=\"wow fadeInRight\"><span>22:00<\/span>\u696d\u52d9\u518d\u958b<\/h4>\r\n\t\t\t\t\t<!--\u753b\u50cf\u5de6 \u3053\u3053\u304b\u3089-->\r\n\t\t\t\t\t<ul class=\"pict_left\">\r\n\t\t\t\t\t\t<li class=\"wow fadeInLeft\"><img src=\"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-content\/themes\/aleph-recruit\/img\/staff\/1day_10_05.jpg\" alt=\"\u95a2\u6771\u5730\u533a S.Y\u3055\u3093\"><\/li>\r\n\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t<div>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInRight\">\u63a5\u5ba2\u3084\u8abf\u7406\u3092\u30b9\u30bf\u30c3\u30d5\u3068\u4e00\u7dd2\u306b\u884c\u3044\u3001\u304a\u5ba2\u69d8\u306e\u7b11\u9854\u3092\u5897\u3084\u3057\u307e\u3059<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInRight\">\u7bc0\u30e1\u30cb\u30e5\u30fc\u306a\u3069\u306e\u5c0e\u5165\u65e5\u524d\u306f\u30dd\u30b9\u30bf\u30fc\u3084\u30e1\u30cb\u30e5\u30fc\u3092\u5165\u308c\u66ff\u3048\u307e\u3059<\/span><br>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInRight\">\u30de\u30cb\u30e5\u30a2\u30eb\u306e\u5909\u66f4\u70b9\u3092\u30b9\u30bf\u30c3\u30d5\u3078\u6307\u5c0e\u3059\u308b\u8cc7\u6599\u4f5c\u6210\u3057\u307e\u3059<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInRight\">\u8ab2\u984c\u306e\u9032\u6357\u3092\u78ba\u8a8d\u3057\u3066\u3001\u4eca\u5f8c\u306e\u8a08\u753b\u3092\u7df4\u308a\u307e\u3059<\/span>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t<!--\u753b\u50cf\u5de6 \u3053\u3053\u307e\u3067-->\r\n\t\t\t\t\t<!--\u753b\u50cf\u53f3 \u3053\u3053\u304b\u3089-->\r\n\t\t\t\t\t<ul class=\"pict_right\">\r\n\t\t\t\t\t\t<li class=\"wow fadeInRight\"><img src=\"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-content\/themes\/aleph-recruit\/img\/staff\/1day_10_04.jpg\" alt=\"\u95a2\u6771\u5730\u533a S.Y\u3055\u3093\"><\/li>\r\n\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t<div>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInLeft\">\u65b0\u305f\u306b\u6c7a\u307e\u3063\u305f\u30eb\u30fc\u30eb\u3092\u30b9\u30bf\u30c3\u30d5\u3078\u6307\u5c0e\u3057\u307e\u3059<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInLeft\">\u98df\u6750\u306e\u5728\u5eab\u3092\u78ba\u8a8d\u3057\u3066\u3001\u5de5\u5834\u3078\u306e\u767a\u6ce8\u3092\u884c\u3044\u307e\u3059<\/span>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInLeft\">\u8ab2\u984c\u306e\u9032\u6357\u3092\u78ba\u8a8d\u3057\u3066\u3001\u4eca\u5f8c\u306e\u8a08\u753b\u3092\u7df4\u308a\u307e\u3059<\/span>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t<!--\u753b\u50cf\u53f3 \u3053\u3053\u307e\u3067-->\r\n\t\t\t\t\t<h4 class=\"wow fadeInRight\"><span>02:00<\/span>\u9000\u793e<\/h4>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<!--\u9000\u52e4-->\r\n\t\t\t\t<div class=\"timeline homecoming\">\r\n\t\t\t\t\t<!--\u753b\u50cf\u5de6 \u3053\u3053\u304b\u3089-->\r\n\t\t\t\t\t<ul class=\"pict_left\">\r\n\t\t\t\t\t\t<li><img src=\"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-content\/themes\/aleph-recruit\/img\/staff\/1day_10_03.jpg\" alt=\"\u95a2\u6771\u5730\u533a S.Y\u3055\u3093\"><\/li>\r\n\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t<div>\r\n\t\t\t\t\t\t\t\t<span class=\"wow fadeInRight\">\u9589\u5e97\u4f5c\u696d\u3092\u884c\u3044\u3001\u7fcc\u671d\u51fa\u52e4\u306e\u793e\u54e1\u3078\u5f15\u304d\u7d99\u304e\u30ce\u30fc\u30c8\u8a18\u5165\u3002\u4eca\u65e5\u306e\u4ed5\u4e8b\u306f\u7d42\u4e86\uff01<\/span>\r\n<span class=\"wow fadeInRight\">\u304a\u75b2\u308c\u69d8\u3067\u3057\u305f\u3002<\/span>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t<!--\u753b\u50cf\u5de6 \u3053\u3053\u307e\u3067-->\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<!--\u6642\u7cfb\u5217 \u3053\u3053\u307e\u3067-->\r\n\t\t\t<\/div>\r\n\t\t\t<!--\u30b3\u30f3\u30c6\u30f3\u30c4 \u3053\u3053\u307e\u3067-->\r\n\r\n\t\t\t<!--\u50cd\u3044\u3066!\u306a\u3053\u3068 \u3053\u3053\u304b\u3089-->\r\n\t\t\t<div class=\"inner_middle cf staff_1day\">\r\n\t\t\t\t<div class=\"btn_area\">\r\n\t\t\t\t\t<div class=\"btn_square_blue wow fadeInUp\">\r\n\t\t\t\t\t\t<a href=\"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-content\/themes\/aleph-recruit\/staff\/interview_10\">\r\n\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-content\/themes\/aleph-recruit\/img\/top\/btn_text_01.png\" alt=\"\u50cd\u3044\u3066!\u306a\u3053\u3068\">\r\n\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<!--\u50cd\u3044\u3066!\u306a\u3053\u3068 \u3053\u3053\u307e\u3067-->\r\n\t\r\n\t","protected":false},"excerpt":{"rendered":"\u3073\u3063\u304f\u308a\u30c9\u30f3\u30ad\u30fcS.Y.\u3055\u3093\u306e1\u65e5 17:00\u51fa\u52e4 \u81ea\u52d5\u8eca\u901a\u52e4 \u6c17\u6301\u3061\u3092\u4ed5\u4e8b\u30e2\u30fc\u30c9\u306b \u30b9\u30bf\u30c3\u30d5\u306e\u7686\u3055\u3093\u306b\u6328\u62f6\u3057\u306a\u304c\u3089\u52e4\u52d9\u72b6\u6cc1\u306e\u78ba\u8a8d \u30b9\u30bf\u30c3\u30d5\u306e\u4f53\u8abf\u30fb\u8eab\u3060\u3057\u306a\u307f\u3092\u78ba\u8a8d \u5236\u670d\u306b\u7740\u66ff\u3048\u3001\u624b\u3092\u3088\u304f\u6d17\u3044\u3001\u52e4\u52d9\u306b\u3080\u3051\u3066\u6e96\u5099OK \u65b0\u4eba [&hellip;]","protected":false},"author":1,"featured_media":0,"parent":5,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-json\/wp\/v2\/pages\/1062"}],"collection":[{"href":"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-json\/wp\/v2\/comments?post=1062"}],"version-history":[{"count":7,"href":"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-json\/wp\/v2\/pages\/1062\/revisions"}],"predecessor-version":[{"id":1398,"href":"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-json\/wp\/v2\/pages\/1062\/revisions\/1398"}],"up":[{"embeddable":true,"href":"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-json\/wp\/v2\/pages\/5"}],"wp:attachment":[{"href":"https:\/\/www.aleph-inc.co.jp\/recruit\/wp-json\/wp\/v2\/media?parent=1062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}